{"id":287,"count":1,"description":"","link":"http:\/\/elevenconsultoria.com.br\/portal\/category\/pnad\/","name":"PNAD","slug":"pnad","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/elevenconsultoria.com.br\/portal\/wp-json\/wp\/v2\/categories\/287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elevenconsultoria.com.br\/portal\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/elevenconsultoria.com.br\/portal\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/elevenconsultoria.com.br\/portal\/wp-json\/wp\/v2\/posts?categories=287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}