{"id":479,"date":"2011-04-29T11:46:00","date_gmt":"2011-04-29T11:46:00","guid":{"rendered":"http:\/\/elevenconsultoria.com.br\/portal\/2011\/04\/29\/nova-versao-do-chrome-11-aceita-comandos-por-voz\/"},"modified":"2011-04-29T11:46:00","modified_gmt":"2011-04-29T11:46:00","slug":"nova-versao-do-chrome-11-aceita-comandos-por-voz","status":"publish","type":"post","link":"http:\/\/elevenconsultoria.com.br\/portal\/2011\/04\/29\/nova-versao-do-chrome-11-aceita-comandos-por-voz\/","title":{"rendered":"Nova vers\u00e3o do Chrome 11 aceita comandos por voz"},"content":{"rendered":"<p><a href=\"http:\/\/1.bp.blogspot.com\/-CIqdU9OvP7w\/Tbql3qTOuVI\/AAAAAAAAABc\/xy94A_G53Mc\/s1600\/chrome.jpg\"><img decoding=\"async\" style=\"display: block; margin: 0px auto 10px; text-align: center; cursor: pointer; width: 138px; height: 133px;\" src=\"http:\/\/1.bp.blogspot.com\/-CIqdU9OvP7w\/Tbql3qTOuVI\/AAAAAAAAABc\/xy94A_G53Mc\/s320\/chrome.jpg\" alt=\"\" id=\"BLOGGER_PHOTO_ID_5600971462254967122\" border=\"0\" \/><\/a><\/p>\n<h2  style=\"text-align: center;font-family:verdana;\"><span style=\"font-size:100%;\">Recurso, por enquanto, s\u00f3 funciona no Google Translate.<\/span><\/h2>\n<div style=\"font-family: verdana;\">\n<p>A Google liberou na \u00faltima quarta-feira (28\/04) a vers\u00e3o est\u00e1vel do <a href=\"http:\/\/idgnow.uol.com.br\/internet\/2011\/03\/23\/nova-versao-beta-do-chrome-suporta-comandos-de-voz\/\">Chrome 11<\/a>.  Agora o navegador conta com um recurso (dispon\u00edvel no padr\u00e3o HTML5) que  dispensa o uso do teclado. Em vez de digitar, o usu\u00e1rio fala ao  microfone e o software transcreve o que \u00e9 dito. Ele, por\u00e9m, s\u00f3 funciona  em sites adaptados para suport\u00e1-lo.<\/p>\n<p>Por enquanto, s\u00f3 o Google Translate tira proveito da fun\u00e7\u00e3o. E apenas  na tradu\u00e7\u00e3o de palavras em ingl\u00eas. Nos testes, ela funcionou  decentemente, mas se complicou mais com frases longas. O curioso \u00e9 que  palavr\u00f5es n\u00e3o s\u00e3o aceitos. Se voc\u00ea falar shit (\u201cmerda\u201d), o aplicativo o  representar\u00e1 em sinais gr\u00e1ficos, no caso, com tr\u00eas sustenidos (###).<\/p>\n<p>Para usar a ferramenta, o usu\u00e1rio deve instalar a \u00faltima vers\u00e3o do  Chrome e entrar no Google Translate. Ele ver\u00e1 o pequeno \u00edcone de um  microfone na caixa de texto. Ao selecion\u00e1-la, s\u00f3 precisar\u00e1 dizer o que  quer esperar o fim do processo. Estranhamente, a ferramenta substitui o  bot\u00e3o para o teclado virtual, o que n\u00e3o tem l\u00f3gica, j\u00e1 que muitos  usu\u00e1rios n\u00e3o possuem um microfone.<\/p>\n<p>O recurso n\u00e3o dever\u00e1 demorar a chegar a outros produtos da Google,  como o mecanismo de pesquisa ou o YouTube \u2013 tal qual j\u00e1 ocorre com o  Android. Para baixar o Chrome 11, clique <a href=\"http:\/\/www.google.com\/chrome\/index.html?hl=pt_br&amp;brand=CHMA&amp;utm_campaign=pt_br&amp;utm_source=pt_br-ha-latam-br-bk&amp;utm_medium=ha&amp;utm_term=google%20chrome\">aqui<\/a>. Ele substituir\u00e1 qualquer vers\u00e3o do browser que voc\u00ea possua na m\u00e1quina.<\/p>\n<p><strong>Mercado<\/strong><br \/>Segundo o instituto de pesquisa Net Applications, o Chrome possui 11,5% do mercado de navegadores. Est\u00e1 atr\u00e1s, portanto, do <a href=\"http:\/\/idgnow.uol.com.br\/internet\/2011\/03\/14\/microsoft-lanca-a-versao-final-do-internet-explorer-9\/\">Internet Explorer<\/a> (55,9%) e do <a href=\"http:\/\/idgnow.uol.com.br\/internet\/2011\/03\/24\/artigo-porque-o-firefox-faz-tanto-sucesso\/\">Firefox<\/a> (21,8%), e \u00e0 frente do Safari (6,6%).<\/p>\n<p><span style=\"font-style: italic; color: rgb(102, 102, 102);font-size:78%;\" >Fonte: IDG NOW!<\/span><\/p>\n<\/p><\/div>\n<p><em><\/em><em><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recurso, por enquanto, s\u00f3 funciona no Google Translate. A Google liberou na \u00faltima quarta-feira (28\/04) a vers\u00e3o est\u00e1vel do Chrome 11. Agora o navegador conta com um recurso (dispon\u00edvel no padr\u00e3o HTML5) que dispensa o uso do teclado. Em vez de digitar, o usu\u00e1rio fala ao microfone e o software transcreve o que \u00e9 dito. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-479","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"http:\/\/elevenconsultoria.com.br\/portal\/wp-json\/wp\/v2\/posts\/479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elevenconsultoria.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elevenconsultoria.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elevenconsultoria.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/elevenconsultoria.com.br\/portal\/wp-json\/wp\/v2\/comments?post=479"}],"version-history":[{"count":0,"href":"http:\/\/elevenconsultoria.com.br\/portal\/wp-json\/wp\/v2\/posts\/479\/revisions"}],"wp:attachment":[{"href":"http:\/\/elevenconsultoria.com.br\/portal\/wp-json\/wp\/v2\/media?parent=479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elevenconsultoria.com.br\/portal\/wp-json\/wp\/v2\/categories?post=479"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elevenconsultoria.com.br\/portal\/wp-json\/wp\/v2\/tags?post=479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}